{"id":4636,"date":"2023-12-08T17:06:54","date_gmt":"2023-12-08T22:06:54","guid":{"rendered":"https:\/\/www.canadianhelicopters.com\/?p=4636"},"modified":"2023-12-08T17:06:55","modified_gmt":"2023-12-08T22:06:55","slug":"la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour","status":"publish","type":"post","link":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/","title":{"rendered":"La saison des contrats de soutien en Antarctique est de retour"},"content":{"rendered":"<p><a href=\"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4631\" src=\"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1.png\" alt=\"\" width=\"1000\" height=\"666\" srcset=\"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1.png 1000w, https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1-300x200.png 300w, https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1-768x511.png 768w, https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1-705x470.png 705w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>L&rsquo;\u00e9t\u00e9 est arriv\u00e9 en Antarctique, et les contrats de soutien de Canadian Helicopters sont \u00e0 nouveau en pleine activit\u00e9. Nous fournissons des services d&rsquo;h\u00e9licopt\u00e8re en soutien aux activit\u00e9s de recherche scientifique en Antarctique depuis plus de 30 ans. Ces activit\u00e9s se d\u00e9roulent pendant les mois d&rsquo;\u00e9t\u00e9 en Antarctique et peuvent inclure des navettes entre le navire et la c\u00f4te, des relev\u00e9s radar et LIDAR, la chasse aux m\u00e9t\u00e9orites, la reconnaissance des glaces, la prise de vues a\u00e9riennes\/photographiques, et le transport de charges pour le d\u00e9ploiement de camps. Sur la photo, vous pouvez voir des membres de l&rsquo;Institut Polaire Fran\u00e7ais Paul-\u00c9mile Victor (IPEV).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9t\u00e9 est arriv\u00e9 en Antarctique, et les contrats de soutien de Canadian Helicopters sont \u00e0 nouveau en pleine activit\u00e9. Nous fournissons des services d&rsquo;h\u00e9licopt\u00e8re en soutien aux activit\u00e9s de recherche scientifique en Antarctique depuis plus de 30 ans. Ces activit\u00e9s se d\u00e9roulent pendant les mois d&rsquo;\u00e9t\u00e9 en Antarctique et peuvent inclure des navettes entre le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,35],"tags":[],"class_list":["post-4636","post","type-post","status-publish","format-standard","hentry","category-in-the-news-4","category-news-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La saison des contrats de soutien en Antarctique est de retour - Canadian Helicopters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La saison des contrats de soutien en Antarctique est de retour - Canadian Helicopters\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;\u00e9t\u00e9 est arriv\u00e9 en Antarctique, et les contrats de soutien de Canadian Helicopters sont \u00e0 nouveau en pleine activit\u00e9. Nous fournissons des services d&rsquo;h\u00e9licopt\u00e8re en soutien aux activit\u00e9s de recherche scientifique en Antarctique depuis plus de 30 ans. Ces activit\u00e9s se d\u00e9roulent pendant les mois d&rsquo;\u00e9t\u00e9 en Antarctique et peuvent inclure des navettes entre le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/\" \/>\n<meta property=\"og:site_name\" content=\"Canadian Helicopters\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-08T22:06:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-08T22:06:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/\"},\"author\":{\"name\":\"Joannah\",\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/#\\\/schema\\\/person\\\/eac8c955bbc1082198b2f064940b44d5\"},\"headline\":\"La saison des contrats de soutien en Antarctique est de retour\",\"datePublished\":\"2023-12-08T22:06:54+00:00\",\"dateModified\":\"2023-12-08T22:06:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/\"},\"wordCount\":129,\"publisher\":{\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/IPEV-1.png\",\"articleSection\":[\"In the News\",\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/\",\"url\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/\",\"name\":\"La saison des contrats de soutien en Antarctique est de retour - Canadian Helicopters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/IPEV-1.png\",\"datePublished\":\"2023-12-08T22:06:54+00:00\",\"dateModified\":\"2023-12-08T22:06:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/IPEV-1.png\",\"contentUrl\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/IPEV-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La saison des contrats de soutien en Antarctique est de retour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/\",\"name\":\"Canadian Helicopters\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/#organization\",\"name\":\"Canadian Helicopters\",\"url\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/CH-logo-EN.png\",\"contentUrl\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/CH-logo-EN.png\",\"width\":230,\"height\":129,\"caption\":\"Canadian Helicopters\"},\"image\":{\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.canadianhelicopters.com\\\/fr\\\/#\\\/schema\\\/person\\\/eac8c955bbc1082198b2f064940b44d5\",\"name\":\"Joannah\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c67286a2ea56070813d8bac69bb0bb49e857abef5729920c8019477d981a824d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c67286a2ea56070813d8bac69bb0bb49e857abef5729920c8019477d981a824d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c67286a2ea56070813d8bac69bb0bb49e857abef5729920c8019477d981a824d?s=96&d=mm&r=g\",\"caption\":\"Joannah\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La saison des contrats de soutien en Antarctique est de retour - Canadian Helicopters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/","og_locale":"fr_FR","og_type":"article","og_title":"La saison des contrats de soutien en Antarctique est de retour - Canadian Helicopters","og_description":"L&rsquo;\u00e9t\u00e9 est arriv\u00e9 en Antarctique, et les contrats de soutien de Canadian Helicopters sont \u00e0 nouveau en pleine activit\u00e9. Nous fournissons des services d&rsquo;h\u00e9licopt\u00e8re en soutien aux activit\u00e9s de recherche scientifique en Antarctique depuis plus de 30 ans. Ces activit\u00e9s se d\u00e9roulent pendant les mois d&rsquo;\u00e9t\u00e9 en Antarctique et peuvent inclure des navettes entre le [&hellip;]","og_url":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/","og_site_name":"Canadian Helicopters","article_published_time":"2023-12-08T22:06:54+00:00","article_modified_time":"2023-12-08T22:06:55+00:00","og_image":[{"url":"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":false,"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/#article","isPartOf":{"@id":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/"},"author":{"name":"Joannah","@id":"https:\/\/www.canadianhelicopters.com\/fr\/#\/schema\/person\/eac8c955bbc1082198b2f064940b44d5"},"headline":"La saison des contrats de soutien en Antarctique est de retour","datePublished":"2023-12-08T22:06:54+00:00","dateModified":"2023-12-08T22:06:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/"},"wordCount":129,"publisher":{"@id":"https:\/\/www.canadianhelicopters.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/#primaryimage"},"thumbnailUrl":"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1.png","articleSection":["In the News","News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/","url":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/","name":"La saison des contrats de soutien en Antarctique est de retour - Canadian Helicopters","isPartOf":{"@id":"https:\/\/www.canadianhelicopters.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/#primaryimage"},"image":{"@id":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/#primaryimage"},"thumbnailUrl":"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1.png","datePublished":"2023-12-08T22:06:54+00:00","dateModified":"2023-12-08T22:06:55+00:00","breadcrumb":{"@id":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/#primaryimage","url":"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1.png","contentUrl":"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2023\/12\/IPEV-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.canadianhelicopters.com\/fr\/la-saison-des-contrats-de-soutien-en-antarctique-est-de-retour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.canadianhelicopters.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"La saison des contrats de soutien en Antarctique est de retour"}]},{"@type":"WebSite","@id":"https:\/\/www.canadianhelicopters.com\/fr\/#website","url":"https:\/\/www.canadianhelicopters.com\/fr\/","name":"Canadian Helicopters","description":"","publisher":{"@id":"https:\/\/www.canadianhelicopters.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.canadianhelicopters.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.canadianhelicopters.com\/fr\/#organization","name":"Canadian Helicopters","url":"https:\/\/www.canadianhelicopters.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.canadianhelicopters.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2020\/10\/CH-logo-EN.png","contentUrl":"https:\/\/www.canadianhelicopters.com\/wp-content\/uploads\/2020\/10\/CH-logo-EN.png","width":230,"height":129,"caption":"Canadian Helicopters"},"image":{"@id":"https:\/\/www.canadianhelicopters.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.canadianhelicopters.com\/fr\/#\/schema\/person\/eac8c955bbc1082198b2f064940b44d5","name":"Joannah","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c67286a2ea56070813d8bac69bb0bb49e857abef5729920c8019477d981a824d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c67286a2ea56070813d8bac69bb0bb49e857abef5729920c8019477d981a824d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c67286a2ea56070813d8bac69bb0bb49e857abef5729920c8019477d981a824d?s=96&d=mm&r=g","caption":"Joannah"}}]}},"_links":{"self":[{"href":"https:\/\/www.canadianhelicopters.com\/fr\/wp-json\/wp\/v2\/posts\/4636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.canadianhelicopters.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.canadianhelicopters.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.canadianhelicopters.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.canadianhelicopters.com\/fr\/wp-json\/wp\/v2\/comments?post=4636"}],"version-history":[{"count":1,"href":"https:\/\/www.canadianhelicopters.com\/fr\/wp-json\/wp\/v2\/posts\/4636\/revisions"}],"predecessor-version":[{"id":4637,"href":"https:\/\/www.canadianhelicopters.com\/fr\/wp-json\/wp\/v2\/posts\/4636\/revisions\/4637"}],"wp:attachment":[{"href":"https:\/\/www.canadianhelicopters.com\/fr\/wp-json\/wp\/v2\/media?parent=4636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.canadianhelicopters.com\/fr\/wp-json\/wp\/v2\/categories?post=4636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.canadianhelicopters.com\/fr\/wp-json\/wp\/v2\/tags?post=4636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}